{"id":7147,"date":"2024-12-19T09:11:05","date_gmt":"2024-12-19T09:11:05","guid":{"rendered":"https:\/\/beenmc.com\/?p=7147"},"modified":"2024-12-20T14:17:26","modified_gmt":"2024-12-20T14:17:26","slug":"we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp","status":"publish","type":"post","link":"https:\/\/beenmc.com\/nl\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/","title":{"rendered":"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp!"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Een nieuw jaar, dat betekent nieuwe of aangescherpte doelen! Wij helpen organisaties om duurzaamheidsambities te realiseren. Hoe zorg je voor een succesvolle en duurzame inbedding, neem je jouw organisatie mee, zorg je voor versnelling \u00e9n benut je de kansen en het onderscheidend vermogen die duurzaamheid kan bieden?<\/p>","protected":false},"author":4,"featured_media":7151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[41],"tags":[],"expertise":[86],"service":[111,89],"transition":[],"class_list":["post-7147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","expertise-food","service-b-corp","service-strategy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! - Event in Dutch - BeenMC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beenmc.com\/nl\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! - Event in Dutch - BeenMC\" \/>\n<meta property=\"og:description\" content=\"Een nieuw jaar, dat betekent nieuwe of aangescherpte doelen! Wij helpen organisaties om duurzaamheidsambities te realiseren. Hoe zorg je voor een succesvolle en duurzame inbedding, neem je jouw organisatie mee, zorg je voor versnelling \u00e9n benut je de kansen en het onderscheidend vermogen die duurzaamheid kan bieden?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beenmc.com\/nl\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/\" \/>\n<meta property=\"og:site_name\" content=\"BeenMC\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-19T09:11:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T14:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beenmc.com\/wp-content\/uploads\/2024\/12\/top-view-tasty-breakfast-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Been Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Been Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/\"},\"author\":{\"name\":\"Been Editor\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/#\\\/schema\\\/person\\\/05cdb05648179ee3e5669d3537504b17\"},\"headline\":\"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! &#8211; Event in Dutch\",\"datePublished\":\"2024-12-19T09:11:05+00:00\",\"dateModified\":\"2024-12-20T14:17:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beenmc.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/top-view-tasty-breakfast-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/\",\"url\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/\",\"name\":\"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! - Event in Dutch - BeenMC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beenmc.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/top-view-tasty-breakfast-scaled.jpg\",\"datePublished\":\"2024-12-19T09:11:05+00:00\",\"dateModified\":\"2024-12-20T14:17:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beenmc.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/top-view-tasty-breakfast-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/beenmc.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/top-view-tasty-breakfast-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beenmc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! &#8211; Event in Dutch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/#website\",\"url\":\"https:\\\/\\\/beenmc.com\\\/\",\"name\":\"BeenMC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beenmc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/#organization\",\"name\":\"BeenMC\",\"url\":\"https:\\\/\\\/beenmc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beenmc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGO-4.svg\",\"contentUrl\":\"https:\\\/\\\/beenmc.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGO-4.svg\",\"width\":257,\"height\":130,\"caption\":\"BeenMC\"},\"image\":{\"@id\":\"https:\\\/\\\/beenmc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beenmc.com\\\/#\\\/schema\\\/person\\\/05cdb05648179ee3e5669d3537504b17\",\"name\":\"Been Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8db0bdce23d70bc0eaebe6a14440df5f0fa3115b9035f1bcab7e4e0a8c7fa947?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8db0bdce23d70bc0eaebe6a14440df5f0fa3115b9035f1bcab7e4e0a8c7fa947?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8db0bdce23d70bc0eaebe6a14440df5f0fa3115b9035f1bcab7e4e0a8c7fa947?s=96&d=mm&r=g\",\"caption\":\"Been Editor\"},\"url\":\"https:\\\/\\\/beenmc.com\\\/nl\\\/author\\\/beeneditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! - Event in Dutch - BeenMC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beenmc.com\/nl\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/","og_locale":"nl_NL","og_type":"article","og_title":"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! - Event in Dutch - BeenMC","og_description":"Een nieuw jaar, dat betekent nieuwe of aangescherpte doelen! Wij helpen organisaties om duurzaamheidsambities te realiseren. Hoe zorg je voor een succesvolle en duurzame inbedding, neem je jouw organisatie mee, zorg je voor versnelling \u00e9n benut je de kansen en het onderscheidend vermogen die duurzaamheid kan bieden?","og_url":"https:\/\/beenmc.com\/nl\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/","og_site_name":"BeenMC","article_published_time":"2024-12-19T09:11:05+00:00","article_modified_time":"2024-12-20T14:17:26+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/beenmc.com\/wp-content\/uploads\/2024\/12\/top-view-tasty-breakfast-scaled.jpg","type":"image\/jpeg"}],"author":"Been Editor","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Been Editor","Geschatte leestijd":"3 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/#article","isPartOf":{"@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/"},"author":{"name":"Been Editor","@id":"https:\/\/beenmc.com\/#\/schema\/person\/05cdb05648179ee3e5669d3537504b17"},"headline":"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! &#8211; Event in Dutch","datePublished":"2024-12-19T09:11:05+00:00","dateModified":"2024-12-20T14:17:26+00:00","mainEntityOfPage":{"@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/"},"wordCount":14,"publisher":{"@id":"https:\/\/beenmc.com\/#organization"},"image":{"@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/#primaryimage"},"thumbnailUrl":"https:\/\/beenmc.com\/wp-content\/uploads\/2024\/12\/top-view-tasty-breakfast-scaled.jpg","articleSection":["News"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/","url":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/","name":"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! - Event in Dutch - BeenMC","isPartOf":{"@id":"https:\/\/beenmc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/#primaryimage"},"image":{"@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/#primaryimage"},"thumbnailUrl":"https:\/\/beenmc.com\/wp-content\/uploads\/2024\/12\/top-view-tasty-breakfast-scaled.jpg","datePublished":"2024-12-19T09:11:05+00:00","dateModified":"2024-12-20T14:17:26+00:00","breadcrumb":{"@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/#primaryimage","url":"https:\/\/beenmc.com\/wp-content\/uploads\/2024\/12\/top-view-tasty-breakfast-scaled.jpg","contentUrl":"https:\/\/beenmc.com\/wp-content\/uploads\/2024\/12\/top-view-tasty-breakfast-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/beenmc.com\/we-trappen-2025-af-met-3-ontbijtsessies-over-csrd-en-b-corp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beenmc.com\/"},{"@type":"ListItem","position":2,"name":"We trappen 2025 af met 3 ontbijtsessies over CSRD en B Corp! &#8211; Event in Dutch"}]},{"@type":"WebSite","@id":"https:\/\/beenmc.com\/#website","url":"https:\/\/beenmc.com\/","name":"BeenMC","description":"","publisher":{"@id":"https:\/\/beenmc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beenmc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/beenmc.com\/#organization","name":"BeenMC","url":"https:\/\/beenmc.com\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/beenmc.com\/#\/schema\/logo\/image\/","url":"https:\/\/beenmc.com\/wp-content\/uploads\/2023\/08\/LOGO-4.svg","contentUrl":"https:\/\/beenmc.com\/wp-content\/uploads\/2023\/08\/LOGO-4.svg","width":257,"height":130,"caption":"BeenMC"},"image":{"@id":"https:\/\/beenmc.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beenmc.com\/#\/schema\/person\/05cdb05648179ee3e5669d3537504b17","name":"Been Editor","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/8db0bdce23d70bc0eaebe6a14440df5f0fa3115b9035f1bcab7e4e0a8c7fa947?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8db0bdce23d70bc0eaebe6a14440df5f0fa3115b9035f1bcab7e4e0a8c7fa947?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8db0bdce23d70bc0eaebe6a14440df5f0fa3115b9035f1bcab7e4e0a8c7fa947?s=96&d=mm&r=g","caption":"Been Editor"},"url":"https:\/\/beenmc.com\/nl\/author\/beeneditor\/"}]}},"_links":{"self":[{"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/posts\/7147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/comments?post=7147"}],"version-history":[{"count":9,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/posts\/7147\/revisions"}],"predecessor-version":[{"id":7161,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/posts\/7147\/revisions\/7161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/media\/7151"}],"wp:attachment":[{"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/media?parent=7147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/categories?post=7147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/tags?post=7147"},{"taxonomy":"expertise","embeddable":true,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/expertise?post=7147"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/service?post=7147"},{"taxonomy":"transition","embeddable":true,"href":"https:\/\/beenmc.com\/nl\/wp-json\/wp\/v2\/transition?post=7147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}